{"id":185,"date":"2024-02-16T15:02:59","date_gmt":"2024-02-16T18:02:59","guid":{"rendered":"https:\/\/difusao.tech\/blog\/?p=185"},"modified":"2025-06-04T17:25:21","modified_gmt":"2025-06-04T20:25:21","slug":"dicionario-de-ti","status":"publish","type":"post","link":"https:\/\/difusao.tech\/blog\/dicionario-de-ti\/","title":{"rendered":"Dicion\u00e1rio de TI"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"260\" src=\"https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2024\/02\/dicionario.png\" alt=\"\" class=\"wp-image-201\" style=\"width:275px;height:auto\" srcset=\"https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2024\/02\/dicionario.png 452w, https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2024\/02\/dicionario-300x173.png 300w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-htgb-block-glossary is-style-default hg-glossary\"><div id=\"hg-uid\" class=\"is-style-default hg-glossary hg-glossary\"><div class=\"hg-glossary__header\"><div class=\"hg-search\"><input data-role=\"hg-search-input\" placeholder=\"Search the Glossary...\"\/><\/div><div class=\"hg-nav\"><a class=\"htgb_active_nav\" data-role=\"hg-nav-selectable\" href=\"#all\" data-name=\"all\">All<\/a><a href=\"#A\" data-name=\"A\" data-role=\"hg-nav-selectable\" class=\"\">A<\/a><a href=\"#B\" data-name=\"B\" data-role=\"hg-nav-selectable\" class=\"\">B<\/a><a href=\"#D\" data-name=\"D\" data-role=\"hg-nav-selectable\" class=\"\">D<\/a><a href=\"#E\" data-name=\"E\" data-role=\"hg-nav-selectable\" class=\"\">E<\/a><a href=\"#K\" data-name=\"K\" data-role=\"hg-nav-selectable\" class=\"\">K<\/a><a href=\"#L\" data-name=\"L\" data-role=\"hg-nav-selectable\" class=\"\">L<\/a><a href=\"#S\" data-name=\"S\" data-role=\"hg-nav-selectable\" class=\"\">S<\/a><a href=\"#V\" data-name=\"V\" data-role=\"hg-nav-selectable\" class=\"\">V<\/a><\/div><\/div><div class=\"hg-content\"><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">A<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon AMI<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Amazon Machine Image, imagens prontas para utiliza\u00e7\u00e3o. Ver EC2.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon API Gateway<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon API Gateway \u00e9 um servi\u00e7o gerenciado que permite que desenvolvedores criem, publiquem, mantenham, monitorem e protejam APIs em qualquer escala com facilidade. APIs agem como a \u201cporta de entrada\u201d para aplicativos acessarem dados, l\u00f3gica de neg\u00f3cios ou funcionalidade de seus servi\u00e7os de back-end.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon AppFlow<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Automatizar fluxos de dados entre software como servi\u00e7o (SaaS) e servi\u00e7os da AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Aurora<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">SGBD da Amazon onde pode ser utilizado para PostgreSQL e mySql.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon CloudFront<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon CloudFront \u00e9 um servi\u00e7o de rede de entrega de conte\u00fado (CDN) criado para alta performance, seguran\u00e7a e conveni\u00eancia do desenvolvedor.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Code Whisperer<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon CodeWhisperer gera sugest\u00f5es de c\u00f3digo que variam de trechos a fun\u00e7\u00f5es completas em tempo real no IDE, com base em seus coment\u00e1rios e no c\u00f3digo existente. Ele tamb\u00e9m oferece suporte a conclus\u00f5es de CLI e tradu\u00e7\u00e3o de linguagem natural para bash na linha de comando.<br><br>V\u00eddeo de configura\u00e7\u00e3o do CodeWhisperer no VS Code no link a seguir: <a href=\"https:\/\/youtu.be\/rHNMfOK8pWI?si=T57m6CbCqRXYG-5n\" target=\"_blank\" rel=\"noreferrer noopener\">V\u00eddeo no Youtube<\/a><\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Comprehend<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Comprehend \u00e9 um servi\u00e7o de processamento de linguagem natural (NLP) que usa machine learning para descobrir insights e rela\u00e7\u00f5es nos textos.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Comprehend Medical<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Comprehend Medical \u00e9 um servi\u00e7o de processamento de linguagem natural (NLP) qualificado para HIPAA que usa machine learning pr\u00e9-treinado para <strong>entender e extrair dados de sa\u00fade de textos m\u00e9dicos<\/strong>, como prescri\u00e7\u00f5es, procedimentos ou diagn\u00f3sticos.<br><\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon EBS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Elastic Block Store (Amazon EBS) \u00e9 um servi\u00e7o de armazenamento em blocos f\u00e1cil de usar, escal\u00e1vel e de alta performance projetado para o Amazon Elastic Compute Cloud (Amazon EC2).<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon EC2<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Amazon Elastic Compute Cloud (Amazon EC2) Camada de computa\u00e7\u00e3o em nuvem, equivalente a um VPS. Ver AMI.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon ECS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Elastic Container Service (ECS) \u00e9 um servi\u00e7o totalmente gerenciado de orquestra\u00e7\u00e3o de cont\u00eaineres que ajuda a implantar, gerenciar e escalar aplica\u00e7\u00f5es em cont\u00eaineres de maneira mais eficiente. Ele se integra totalmente ao ambiente da AWS para fornecer uma solu\u00e7\u00e3o f\u00e1cil de usar para executar workloads de cont\u00eaineres na nuvem e on-premises com atributos de seguran\u00e7a avan\u00e7ados usando o Amazon ECS Anywhere.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon EMR<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Amazon EMR \u00e9 a solu\u00e7\u00e3o de big data em nuvem l\u00edder do setor para processamento de dados, an\u00e1lise interativa e machine learning que usa estruturas de c\u00f3digo aberto, como Apache Spark, Apache Hive e Presto.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon EventBridge<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Crie aplica\u00e7\u00f5es orientadas por eventos em escala na AWS, sistemas existentes ou aplica\u00e7\u00f5es SaaS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon GuardDuty<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon GuardDuty \u00e9 um servi\u00e7o de detec\u00e7\u00e3o de amea\u00e7as que monitora continuamente suas contas e workloads da AWS para detectar atividades mal-intencionadas e entrega descobertas de seguran\u00e7a detalhadas, permitindo visibilidade e corre\u00e7\u00e3o.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Inspector<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Inspector detecta automaticamente as workloads, como inst\u00e2ncias do Amazon EC2, cont\u00eaineres e fun\u00e7\u00f5es do Lambda, e as verifica em busca de vulnerabilidades de software e exposi\u00e7\u00e3o n\u00e3o intencional da rede.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Kinesis Data Firehose<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Data Firehose oferece a maneira mais f\u00e1cil de adquirir, transformar e entregar fluxos de dados em segundos para data lakes, data warehouses e servi\u00e7os de an\u00e1lise. Para usar o Amazon Data Firehose, configure um fluxo com a origem, o destino e as transforma\u00e7\u00f5es necess\u00e1rias. O Amazon Data Firehose processa continuamente o fluxo, escala automaticamente com base na quantidade de dados dispon\u00edveis e o entrega em segundos.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Kinesis Data Streams<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Kinesis Data Streams \u00e9 um servi\u00e7o sem servidor que torna f\u00e1cil a captura, o processamento e o armazenamento de transmiss\u00f5es de dados em qualquer escala para analisar usando ferramenta de BI de sua prefer\u00eancia.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Lambda<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Lambda \u00e9 um servi\u00e7o de computa\u00e7\u00e3o que executa seu c\u00f3digo em resposta a eventos e gerencia automaticamente os recursos de computa\u00e7\u00e3o, tornando-se a maneira mais r\u00e1pida de transformar uma ideia em aplica\u00e7\u00f5es de produ\u00e7\u00e3o modernas e com tecnologia sem servidor.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Lightsail<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Servi\u00e7o da AWS para criar aplica\u00e7\u00f5es e sites com recursos de nuvem pr\u00e9-configurados com pilhas como LAMP, Ngnix, MEAN e Node.js, utilize tamb\u00e9m aplica\u00e7\u00f5es pr\u00e9-configuradas como WordPress, Magento, Prestashop e Joomla.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Macie<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Prote\u00e7\u00e3o de dados confi\u00e1veis. O Amazon Macie \u00e9 um servi\u00e7o de seguran\u00e7a e privacidade de dados que usa machine learning (ML) e correspond\u00eancia de padr\u00f5es para descobrir e proteger seus dados confidenciais.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon OpenSearch Service<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon OpenSearch Service facilita a execu\u00e7\u00e3o de an\u00e1lises de log interativas, o monitoramento de aplica\u00e7\u00f5es em tempo real, pesquisas de sites e muito mais. O OpenSearch \u00e9 um conjunto de pesquisa e an\u00e1lise de c\u00f3digo aberto distribu\u00eddo derivado do Elasticsearch.\u00a0O Amazon OpenSearch Service oferece as vers\u00f5es mais recentes do OpenSearch, suporte para 19 vers\u00f5es do Elasticsearch (vers\u00f5es de 1.5 a 7.10), bem como recursos de visualiza\u00e7\u00e3o fornecidos pelo OpenSearch Dashboards e Kibana (vers\u00f5es de 1.5 a 7.10). O Amazon OpenSearch Service atualmente tem dezenas de milhares de clientes ativos com centenas de milhares de clusters sob gerenciamento processando centenas de trilh\u00f5es de solicita\u00e7\u00f5es por m\u00eas.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Q<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">IA Generativa da Amazon que pode ser utilizada como extes\u00e3o no VS Code e outras IDEs ou no proprio site de gerecimanto de servi\u00e7os AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon QuickSight<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon QuickSight permite que todos em sua organiza\u00e7\u00e3o entendam seus dados por meio de perguntas em linguagem natural, do uso de pain\u00e9is interativos ou procurando automaticamente padr\u00f5es e discrep\u00e2ncias com tecnologia de machine learning.<br>\u00c9 o servi\u00e7o de BI sem servidor da AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon RDS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Banco de dados, RDS vem de Relational Database Service.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Redshift<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Redshift usa SQL para analisar dados estruturados e semiestruturados em data warehouses, bancos de dados operacionais e data lakes, usando hardware e machine learning criados pela AWS para oferecer a melhor rela\u00e7\u00e3o entre pre\u00e7o e performance em qualquer escala.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Rekognition<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Automatize e reduza o custo de seu reconhecimento de imagem e an\u00e1lise de v\u00eddeo com machine learning.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon S3<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Simple Storage Service o S3, armazenamento de arquivos, equivalente ao servidor de arquivos.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon S3 Object Lock<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Prote\u00e7\u00e3o de dados contra eventos de ransomware com imutabilidade em n\u00edvel de objeto para proteger objetos de exclus\u00f5es e substitui\u00e7\u00f5es acidentais ou mal-intencionadas<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon SageMaker<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Crie, treine e implante modelos de machine learning para qualquer caso de uso com infraestrutura, ferramentas e fluxos de trabalho totalmente gerenciados.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon SNS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Simples notification service \u00e9 o servi\u00e7o de notificacao, que pode ser por email, SMS e http end point.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon SQS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Servi\u00e7o de notificacao e mensagens da AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Amazon Textract<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Textract corresponde a um servi\u00e7o de machine learning (ML) que extrai automaticamente textos impressos ou manuscritos, elementos de layout e dados de documentos digitalizados. Esse recurso faz mais do que o simples reconhecimento \u00f3ptico de caracteres (OCR): ele identifica, entende e extrai dados espec\u00edficos de documentos.\u00a0<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Amazon Web Services, diversos servi\u00e7os Web da Amazon.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Athena<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon Athena \u00e9 um servi\u00e7o de an\u00e1lise interativo e sem servidor criado em frameworks de c\u00f3digo aberto, com suporte a formatos de tabela e arquivo abertos. O Athena fornece uma maneira simplificada e flex\u00edvel de analisar petabytes de dados onde eles residem. Analise dados ou crie aplica\u00e7\u00f5es a partir de um data lake do Amazon Simple Storage Service (S3) e mais de 30 fontes de dados, incluindo fontes de dados on-premises ou outros sistemas em nuvem usando SQL ou Python. O Athena \u00e9 constru\u00eddo com mecanismos Trino e Presto de c\u00f3digo aberto e frameworks Apache Spark, sem necessidade de provisionamento ou configura\u00e7\u00e3o.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Auto Escaling<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Configura\u00e7\u00e3o feita para suportar a demanda, um auto escaling corretamente configurado vai permitir que sua aplica\u00e7\u00e3o fique dispon\u00edvel e encerre instancias quando a demanda diminuir, balenceando os custo de acordo com a demanda; Geralmente usado em EC2. Ver EC2 e Lauch Configuration.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Batch<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Servi\u00e7o da AWS para processamento em lote, treinamento de modelo de machine learning e an\u00e1lise em qualquer escala<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Bucket<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Cada objeto no Amazon S3 \u00e9 armazenado em um bucket. Antes que voc\u00ea possa armazenar dados no Amazon S3, \u00e9 necess\u00e1rio criar um bucket do S3. Pense como uma unidade de armazenamento ou um diret\u00f3rio que esta sendo criado para uma determinada funcionalidade de armazenamento.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Certificate Manager<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Use o AWS Certificate Manager (ACM) para provisionar, gerenciar e implantar certificados SSL\/TLS p\u00fablicos e privados para uso com servi\u00e7os da AWS e seus recursos internos conectados. O ACM elimina processos manuais demorados, como compra, upload e renova\u00e7\u00e3o de certificados SSL\/TLS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS CloudTrail<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Visualizador de logs de acesso; O AWS CloudTrail monitora e registra a atividade da conta por toda a infraestrutura da AWS, oferecendo controle sobre o armazenamento, an\u00e1lise e a\u00e7\u00f5es de remedia\u00e7\u00e3o.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS CloudWatch<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Amazon CloudWatch \u00e9 um servi\u00e7o que monitora aplica\u00e7\u00f5es, responde \u00e0s mudan\u00e7as de desempenho, otimiza o uso de recursos e fornece insights sobre a integridade operacional. Ao coletar dados de todos os recursos da AWS, o CloudWatch fornece visibilidade sobre o desempenho de todo o sistema e permite que os usu\u00e1rios definam alarmes, reajam automaticamente \u00e0s mudan\u00e7as e obtenham uma vis\u00e3o unificada da integridade operacional.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Config<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Config avalia, audita e avalia continuamente as configura\u00e7\u00f5es e os relacionamentos de seus recursos na AWS, no local e em outras nuvens; <strong>Audite e avalie as configura\u00e7\u00f5es de seus recursos.<\/strong><\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Connection Draining<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Com o Connection Draining ativo em seu ELB ele garante que todas as inst\u00e2ncias removidas do dom\u00ednio do load balancer finanlizem as requisi\u00e7\u00f5es antes de serem removidas.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Data Pipeline<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Data Pipeline \u00e9 um servi\u00e7o web que voc\u00ea pode usar para automatizar a movimenta\u00e7\u00e3o e a transforma\u00e7\u00e3o de dados. Com o AWS Data Pipeline, voc\u00ea pode definir fluxos de trabalho dirigidos por dados para que as tarefas possam ser dependentes da conclus\u00e3o bem-sucedida das tarefas anteriores. Voc\u00ea define os par\u00e2metros das transforma\u00e7\u00f5es dos seus dados, e o AWS Data Pipeline imp\u00f5e a l\u00f3gica configurada.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS DMS Data Migration Service<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Cria uma r\u00e9plica do seu banco de dados on-premises para os servidores da AWS, servi\u00e7o para facilitar a migra\u00e7\u00e3o.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS DyamondDB<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Banco de dados n\u00e3o relacional.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS EC2 Image Builder<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O Construtor de imagens do EC2 simplifica a constru\u00e7\u00e3o, o teste e a implanta\u00e7\u00e3o de m\u00e1quinas virtuais e imagens de cont\u00eainer para uso no AWS ou on-premise.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Elastic Beanstalk<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Elastic Beanstalk oferece suporte a aplica\u00e7\u00f5es Web redigidas em muitas linguagens e framewoks bastante utilizados. Ele requer pouca ou nenhuma altera\u00e7\u00e3o de c\u00f3digo para passar do computador de desenvolvimento para a nuvem. As op\u00e7\u00f5es de desenvolvimento para implantar suas aplica\u00e7\u00f5es Web incluem Java, .NET, Node.js, PHP, Ruby, Python, Go e Docker; Com ele voc\u00ea vai implantar e dimensione aplica\u00e7\u00f5es da Web.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Elastic Load Balancer<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">\u00c9 um servi\u00e7o feito para distribuir os tr\u00e1fegos de entrada entre v\u00e1rias inst\u00e2ncias EC2. Ver EC2.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Firewall Manager<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Firewall Manager \u00e9 um servi\u00e7o de gerenciamento de seguran\u00e7a que permite configurar e gerenciar regras de firewall de maneira centralizada em todas as contas e aplica\u00e7\u00f5es no\u00a0AWS Organizations. \u00c0 medida que novos aplica\u00e7\u00f5es e recursos s\u00e3o criados, o Firewall Manager facilita a aplica\u00e7\u00e3o de conformidade em aplica\u00e7\u00f5es e recursos, for\u00e7ando um conjunto comum de regras de seguran\u00e7a.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Glue<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Glue \u00e9 um servi\u00e7o de integra\u00e7\u00e3o de dados com tecnologia sem servidor que facilita a descoberta, prepara\u00e7\u00e3o, movimenta\u00e7\u00e3o e integra\u00e7\u00e3o de dados de v\u00e1rias fontes para an\u00e1lise, machine learning (ML) e desenvolvimento de aplica\u00e7\u00f5es.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Health Check<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Verifica problemas com o servi\u00e7o, a sa\u00fade da sua inst\u00e2ncia, feita geralmente atrav\u00e9s de um end-point.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS IAM<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Identidade e gerenciamento de acesso, seria o gerenciamento de usu\u00e1rios.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Key Management Service (AWS KMS)<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Com o AWS Key Management Service (AWS KMS), voc\u00ea pode criar, gerenciar e controlar chaves criptogr\u00e1ficas nas suas aplica\u00e7\u00f5es e servi\u00e7os da AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Launch Configuration<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Um template de EC2 que vai ser utilizado para subir inst\u00e2ncias com Auto Escaling. Ver Scale OUT e Scale IN.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Outposts<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Outposts \u00e9 uma fam\u00edlia de solu\u00e7\u00f5es totalmente gerenciadas que fornecem infraestrutura e servi\u00e7os da AWS para praticamente qualquer local da borda ou on-premises. S\u00e3o equipamentos que s\u00e3o instalados localmente na empresa, fazendo com que ela seja uma parte integrante do cloud da AWS mas de forma prinvada.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS S3 Select<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Otimiza a busca de objetos reduzindo os custos de consulta em at\u00e9 80%.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS S3 Transfer Acceleration<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Ferramentas de acelera\u00e7\u00e3o de transfer\u00eancia de dados que incluem, AWS Snowball, Snowball Edge e Snowmobile, utilizada para grandes volumes de dados a serem transferidos para um bucket S3. Ver Bucket S3.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Scale IN<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Termina um nova inst\u00e2ncia. Ver Auto Escaling<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Scale OUT<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Inicia uma nova inst\u00e2ncia. Ver Auto Escaling.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS SCT<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Convers\u00e3o de schemas de banco de dados para migra\u00e7\u00e3o.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Secrets Manager<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Secrets Manager ajuda voc\u00ea a gerenciar, recuperar e alternar credenciais de banco de dados, chaves de API e outros segredos ao longo de seus ciclos de vida.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Shield<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Shield \u00e9 um servi\u00e7o gerenciado de prote\u00e7\u00e3o contra DDoS que protege as aplica\u00e7\u00f5es em execu\u00e7\u00e3o na AWS.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Storage Gateway<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Conecta ambientes locais ao S3. Ver Amazon S3.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Trusted Advisor<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">O AWS Trusted Advisor ajuda voc\u00ea a otimizar custos, aumentar o desempenho, melhorar a seguran\u00e7a e a resili\u00eancia e operar em grande escala na nuvem. O Trusted Advisor avalia continuamente seu ambiente da AWS usando verifica\u00e7\u00f5es de pr\u00e1ticas recomendadas entre as categorias de otimiza\u00e7\u00e3o de custos, performance, resili\u00eancia, seguran\u00e7a, excel\u00eancia operacional e limites de servi\u00e7o, e recomenda a\u00e7\u00f5es para remediar todos os desvios em rela\u00e7\u00e3o \u00e0s pr\u00e1ticas recomendadas.<\/dd><\/dl><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">AWS Well-Architected Tools<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Analisar as cargas de trabalho (workloads), planejar quais servi\u00e7os ser\u00e3o utilizados com base nos pilares Well-Architected, implantar e manter.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">B<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Bastion host<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Os Bastion Hosts fornecem um ponto de entrada externo para uma rede de nuvem privada virtual (VPC) que cont\u00e9m VMs sem endere\u00e7os IP externos. Como uma &#8220;passagem secreta&#8221; para a rede privada, onde o administrador executa suas tarefas.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">D<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Data Warehouse<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Um data warehouse centraliza e consolida grandes quantidades de dados de v\u00e1rias fontes. Seus recursos anal\u00edticos permitem que as organiza\u00e7\u00f5es obtenham informa\u00e7\u00f5es de neg\u00f3cios \u00fateis de seus dados para melhorar a tomada de decis\u00f5es. Com o tempo, cria-se um registro hist\u00f3rico que pode ser inestim\u00e1vel para cientistas de dados e analistas de neg\u00f3cios. Devido a esses recursos, um data warehouse pode ser considerado como a \u201c\u00fanica fonte confi\u00e1vel\u201d de uma organiza\u00e7\u00e3o.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">E<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">ETL<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">ETL (Extract, transform, Load) \u00e9 a sigla para o processo de extrair, transformar e carregar. \u00c9 uma forma tradicionalmente aceita para que as organiza\u00e7\u00f5es combinem dados de v\u00e1rios sistemas em um \u00fanico banco de dados, reposit\u00f3rio de dados, armazenamento de dados ou data lake.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">K<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Kerberos<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">\u00c9 um protocolo de autentica\u00e7\u00e3o de rede, que garante a seguran\u00e7a em sistemas de computadores, principalmente em redes n\u00e3o seguras.\u00a0Ele utiliza um sistema de chaves secretas compartilhadas para autenticar usu\u00e1rios em um ambiente de rede, oferecendo autentica\u00e7\u00e3o m\u00fatua, integridade de dados e privacidade.\u00a0<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">L<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Lustre File System<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Lustre \u00e9 um sistema de arquivos paralelo usado para clusters e ambientes de computa\u00e7\u00e3o de alto desempenho (HPC).; \u00c9 um tipo de sistema de arquivos distribu\u00eddo . No entanto, a diferen\u00e7a est\u00e1 na forma como os dados e metadados s\u00e3o armazenados. Os sistemas de arquivos distribu\u00eddos suportam um \u00fanico namespace global, assim como os sistemas de arquivos paralelos , mas um sistema de arquivos paralelo divide os arquivos em blocos de dados e espalha os dados dos arquivos por v\u00e1rios servidores de armazenamento, que podem ser gravados e lidos em paralelo.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">S<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">Serverless<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Serverless \u00e9 um modelo de desenvolvimento nativo em nuvem para cria\u00e7\u00e3o e execu\u00e7\u00e3o de aplica\u00e7\u00f5es sem servidores. Apesar de ser sem servidor, ele ainda existe, s\u00f3 n\u00e3o existe a necessidade de intera\u00e7\u00e3o para o desenvolvimento.<\/dd><\/dl><\/div><div class=\"hg-letter-section\" data-role=\"hg-section\"><span class=\"hg-content__letter\" data-role=\"hg-section-letter\">V<\/span><dl class=\"hg-item\" data-role=\"hg-item\"><dt class=\"hg-item-title\" data-role=\"hg-item-title\">VPC<\/dt><dd class=\"hg-item-description\" data-role=\"hg-item-description\">Virtual Private Clouds, Nuvem Virtual Privada.<\/dd><\/dl><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,25,26,29,32,35,38,150,41,43,30,1,55],"tags":[205,204,206,207],"class_list":["post-185","post","type-post","status-publish","format-standard","hentry","category-aplicativos-gnu-linux","category-aplicativos-para-android","category-aplicativos-windows","category-design-animacao-e-tratamento-de-imagens","category-eletronicos","category-gestao","category-gnu-linux-bsd-unix-like-e-software-livre","category-hacker","category-inteligencia-artificial","category-internet","category-programacao-e-desenvolvimento","category-redes","category-seguranca-da-informacao","tag-dicionario","tag-dicionario-de-ti","tag-glossario","tag-glossario-de-ti"],"_links":{"self":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":41,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/185\/revisions"}],"predecessor-version":[{"id":649,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/185\/revisions\/649"}],"wp:attachment":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/categories?post=185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/tags?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}