{"id":41,"date":"2023-04-22T20:56:32","date_gmt":"2023-04-22T23:56:32","guid":{"rendered":"https:\/\/difusao.tech\/blog\/?p=41"},"modified":"2023-08-23T13:53:36","modified_gmt":"2023-08-23T16:53:36","slug":"lamp-instalando-o-apache-mysql-php8-no-ubuntu-20-04","status":"publish","type":"post","link":"https:\/\/difusao.tech\/blog\/lamp-instalando-o-apache-mysql-php8-no-ubuntu-20-04\/","title":{"rendered":"LAMP \u2013 Instalando o Apache + Mysql + PHP8 no Ubuntu 20.04"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.fasim.com.br\/wp-content\/uploads\/2021\/10\/lamp.png\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>O que \u00e9 o LAMP?<\/strong><\/p>\n\n\n\n<p>LAMP \u00e9 uma combina\u00e7\u00e3o de softwares de c\u00f3digo aberto. Seu nome \u00e9 um acr\u00f4nimo reunindo as iniciais de seus quatro componentes base: Linux, Apache, MySQL e PHP. Trata-se de uma das primeiras plataformas de software de c\u00f3digo aberto para a rede e continua sendo uma das maneiras mais comuns de fornecer aplica\u00e7\u00f5es web.<\/p>\n\n\n\n<p><strong>Linux:&nbsp;<\/strong>sistema operacional<br>Linux \u00e9 um sistema operacional (OS) livre e de c\u00f3digo aberto, que existe desde meados da d\u00e9cada de 1990. Hoje, ele tem uma extensa base de usu\u00e1rios em todo o mundo.<\/p>\n\n\n\n<p><strong>Apache:<\/strong>&nbsp;servidor web<br>O servidor web Apache processa solicita\u00e7\u00f5es e serve os ativos web via HTTP para que a aplica\u00e7\u00e3o seja acess\u00edvel a qualquer pessoa de dom\u00ednio p\u00fablico, por meio de uma simples URL. Desenvolvido e mantido por uma comunidade aberta, \u00e9 um servidor maduro e rico em recursos, que roda uma grande parte dos sites, atualmente, na Internet.<\/p>\n\n\n\n<p><strong>MySQL:<\/strong>&nbsp;banco de dados<br>O MySQL \u00e9 um sistema de gerenciamento de banco de dados relacional de c\u00f3digo aberto para armazenamento de dados de aplica\u00e7\u00f5es. Com MySQL, voc\u00ea pode armazenar todas as suas informa\u00e7\u00f5es em um formato que \u00e9 facilmente consultado com a linguagem SQL.<\/p>\n\n\n\n<p><strong>PHP:<\/strong>&nbsp;linguagem de programa\u00e7\u00e3o<br>A linguagem de script de c\u00f3digo aberto PHP funciona com o Apache para ajudar a criar p\u00e1ginas web din\u00e2micas. Voc\u00ea n\u00e3o pode usar HTML para realizar processos din\u00e2micos, tais como extrair dados de um banco de dados. Para fornecer esse tipo de funcionalidade, basta inserir o c\u00f3digo PHP nas partes de uma p\u00e1gina que voc\u00ea deseja que seja din\u00e2mica e \u00e9 ai que entra o PHP.<\/p>\n\n\n\n<p>Agora vamos a instala\u00e7\u00e3o dessa equipe toda.<br>Temos como base que voc\u00ea j\u00e1 realizou a instala\u00e7\u00e3o do Linux, no nosso caso usamos a vers\u00e3o 20.04.3 LTS do Ubuntu.<\/p>\n\n\n\n<p><strong>1 \u2013 Fa\u00e7a a instala\u00e7\u00e3o do Apache<\/strong><\/p>\n\n\n\n<p>Para instalar o servidor web Apache e outros componentes necess\u00e1rios, v\u00e1 at\u00e9 o diret\u00f3rio e use o seguinte comando:<\/p>\n\n\n\n<p>sudo apt-get update<br>sudo apt-get install apache2<\/p>\n\n\n\n<p>Depois, habilite o servi\u00e7o httpd (Apache2) para que ele abra ap\u00f3s a reinicializa\u00e7\u00e3o:<\/p>\n\n\n\n<p>sudo systemctl enable apache2.service<\/p>\n\n\n\n<p><strong>2 \u2013 Instale o MySQL<\/strong><\/p>\n\n\n\n<p>O MySQL \u00e9 um sistema de gerenciamento de banco de dado de c\u00f3digo aberto robusto e completo, que alimenta muitos dos sites mais movimentados do mundo com base em dados. O software est\u00e1 dispon\u00edvel em formato de pacote ou como c\u00f3digo fonte. O seguinte comando instala o servidor MySQL, o cliente e as depend\u00eancias:<\/p>\n\n\n\n<p>$ sudo apt -y install mysql-server<\/p>\n\n\n\n<p>Habilite e inicie o servi\u00e7o do servidor MySQL:<\/p>\n\n\n\n<p>sudo systemctl enable mysql.service<\/p>\n\n\n\n<p>Termine, executando o script de configura\u00e7\u00e3o do MySQL:<\/p>\n\n\n\n<p>Ser\u00e1 perguntado sobre a for\u00e7a da senha que deseja configurar, se deseja apagar usuarios anonimos e desabilitar login remoto para o root.<\/p>\n\n\n\n<p>Execute o seguinte comando para iniciar as configura\u00e7\u00f5es citadas:<\/p>\n\n\n\n<p>sudo \/usr\/bin\/mysql_secure_installation<\/p>\n\n\n\n<p><strong>3 \u2013 Instala\u00e7\u00e3o do PHP<\/strong><\/p>\n\n\n\n<p>Vamos adicionar o repositorio.<\/p>\n\n\n\n<p>sudo add-apt-repository ppa:ondrej\/php<\/p>\n\n\n\n<p>Em seguida vamos atualizar o apt.<\/p>\n\n\n\n<p>sudo apt update<\/p>\n\n\n\n<p>Agora vamos a instala\u00e7\u00e3o do PHP finalmente, execute o comando:<\/p>\n\n\n\n<p>sudo apt install php8.0 php8.0-intl php8.0-mysql php8.0-sqlite3 php8.0-gd<\/p>\n\n\n\n<p>Vamos verificar se tudo ocorreu bem verificando a vers\u00e3o do PHP, digite:<\/p>\n\n\n\n<p>php -v<\/p>\n\n\n\n<p>Vamos testar.<\/p>\n\n\n\n<p>Abra seu editor de texto favorito e crie um novo arquivo em \/var\/www\/html, chamado info.php:<\/p>\n\n\n\n<p>sudo vi \/var\/www\/html\/info.php<\/p>\n\n\n\n<p>Digite o seguinte no arquivo info.php:<\/p>\n\n\n\n<p>Salve e abra o navegador e coloque no endere\u00e7o do seu servidor e no final coloque \/info.php.<\/p>\n\n\n\n<p>Ficando assim:<\/p>\n\n\n\n<p>ip_do_servidor\/info.php<\/p>\n\n\n\n<p>No meu caso ficou assim: http:\/\/10.5.133.105\/info.php<\/p>\n\n\n\n<p>Vai aparecer uma p\u00e1gina com todas as informa\u00e7\u00f5es do PHP.<\/p>\n\n\n\n<p>Conclu\u00edmos a instala\u00e7\u00e3o de todos os itens.<\/p>\n\n\n\n<p>Itens instalados:<\/p>\n\n\n\n<p>Apache2<br>mysql 8.0.26<br>PHP 8.0.11<\/p>\n\n\n\n<p>No Ubuntu 20.04.3 LTS<\/p>\n\n\n\n<p>Lembrando que essa \u00e9 a configura\u00e7\u00e3o base, muito ainda pode ser feito dentro dessa estrutura para melhorar n\u00e3o s\u00f3 a seguran\u00e7a, mas tamb\u00e9m a usuabilidade do usu\u00e1rio.<\/p>\n\n\n\n<p>Abra\u00e7os e at\u00e9 a pr\u00f3xima<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 o LAMP? LAMP \u00e9 uma combina\u00e7\u00e3o de softwares de c\u00f3digo aberto. Seu nome \u00e9 um<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,38,56],"tags":[97,98,96,102,104,100,99,103,101],"class_list":["post-41","post","type-post","status-publish","format-standard","hentry","category-banco-de-dados","category-gnu-linux-bsd-unix-like-e-software-livre","category-sistemas-operacionais","tag-apache","tag-lamp","tag-mysql","tag-php","tag-php8","tag-phpmyadmin","tag-servidor-mysql","tag-ubuntu-20-04","tag-xampp"],"_links":{"self":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":1,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"predecessor-version":[{"id":42,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/41\/revisions\/42"}],"wp:attachment":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}