{"id":95,"date":"2023-05-15T18:00:00","date_gmt":"2023-05-15T21:00:00","guid":{"rendered":"https:\/\/difusao.tech\/blog\/?p=95"},"modified":"2023-08-23T13:53:35","modified_gmt":"2023-08-23T16:53:35","slug":"adicionar-repositorio-kali-linux-no-debian-11","status":"publish","type":"post","link":"https:\/\/difusao.tech\/blog\/adicionar-repositorio-kali-linux-no-debian-11\/","title":{"rendered":"Adicionar reposit\u00f3rio Kali Linux no Debian 11"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"218\" src=\"https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2023\/05\/image-5.png\" alt=\"\" class=\"wp-image-96\" srcset=\"https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2023\/05\/image-5.png 585w, https:\/\/difusao.tech\/blog\/wp-content\/uploads\/2023\/05\/image-5-300x112.png 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/figure>\n<\/div>\n\n\n<p>Voc\u00ea pensou em usar as ferramentas do Kali em seu Debian para fins de estudos ou sabe l\u00e1 o que voc\u00ea pensou, ent\u00e3o vamos l\u00e1.<\/p>\n\n\n\n<p>Primeiramente vamos acrescentar os repositorios ao nosso sources.list, execute o comando no terminal:<\/p>\n\n\n\n<h1 class=\"wp-block-heading has-white-background-color has-background\" style=\"font-size:15px;font-style:normal;font-weight:400\"><mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">echo &#8220;deb http:\/\/http.kali.org\/kali kali-rolling main non-free contrib&#8221; >> \/etc\/apt\/sources.list<\/mark><\/h1>\n\n\n\n<h1 class=\"wp-block-heading has-white-background-color has-background\" style=\"font-size:15px;font-style:normal;font-weight:400\"><mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">echo &#8220;deb-src http:\/\/http.kali.org\/kali kali-rolling main non-free contrib&#8221; >> \/etc\/apt\/sources.list<\/mark><\/h1>\n\n\n\n<p>Agora quando executamos o comando <mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">apt-get update<\/mark> encontramos um erro na assinatura p\u00fablica deste reposit\u00f3rio, vamos corrigir.<\/p>\n\n\n\n<p>Execute o comando abaixo:<\/p>\n\n\n\n<p><mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">sudo apt-key adv &#8211;keyserver https:\/\/keys.openpgp.org\/vks\/v1\/by-fingerprint\/44C6513A8E4FB3D30875F758ED444FF07D8D0BF6 &#8211;recv-keys ED444FF07D8D0BF6<\/mark><\/p>\n\n\n\n<p>Agora execute o <mark style=\"background-color:#abb8c3\" class=\"has-inline-color\">apt-get update<\/mark> normalmente e agora sem erros e depois instale as ferramentas que precisar.<\/p>\n\n\n\n<p>Segue a lista de ferramentas: https:\/\/www.kali.org\/tools<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea pensou em usar as ferramentas do Kali em seu Debian para fins de estudos ou sabe l\u00e1<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,34,38,55],"tags":[148,147,94,146,145,149],"class_list":["post-95","post","type-post","status-publish","format-standard","hentry","category-aplicativos-gnu-linux","category-forense","category-gnu-linux-bsd-unix-like-e-software-livre","category-seguranca-da-informacao","tag-ap-get-update","tag-apt-key","tag-debian","tag-kali","tag-repositorio-linux","tag-sources-list"],"_links":{"self":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":1,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/95\/revisions"}],"predecessor-version":[{"id":97,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/posts\/95\/revisions\/97"}],"wp:attachment":[{"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/categories?post=95"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/difusao.tech\/blog\/wp-json\/wp\/v2\/tags?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}